{"id":857,"date":"2020-06-28T00:00:00","date_gmt":"2020-06-27T22:00:00","guid":{"rendered":"https:\/\/www.salvaviaggio.com\/blog-new\/2020\/12\/20\/corona-virus\/"},"modified":"2021-05-22T23:35:54","modified_gmt":"2021-05-22T21:35:54","slug":"corona-virus-consigli","status":"publish","type":"post","link":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/","title":{"rendered":"Pandemia riflessioni dell&#8217;Avv. Fabio Collavini"},"content":{"rendered":"<p>Avv. Fabio Collavini la pandemia ha cambiato le abitudini delle persone ed inevitabilmente ha prodotto profondi cambiamenti anche nelle misure di prevenzione. Nel trasporto aereo il coronavirus ha imposto una riduzione delle rotte, specifici controlli sanitari, riduzione dei servizi ed ovviamente tariffe pi\u00f9 elevate. Le compagnie aeree si trovano di fronte a decisioni spesso drastiche, che, tuttavia, si rendono necessarie per poter resistere alla crisi di un mercato completamente fermo. Ovviamente, la prevenzione \u00e8 la linea guida di ogni intervento che, inevitabilmente, cambier\u00e0 il nostro modo di viaggiare. Ogni passeggero avr\u00e0 l\u2019obbligo di utilizzare mascherine sanitarie e abituarsi a mantenere distanze sociali di sicurezza, adeguandosi anche a nuove regole per interagire con il personale di terra ed i membri dell\u2019equipaggio. Cambieranno anche le semplici procedure di imbarco e sbarco subiranno, con inevitabili ripercussioni sulle tempistiche di volo, con allontanamento dei passeggeri dal trasporto aereo con riferimento al corto raggio. La verit\u00e0 \u00e8 che il trasporto aereo si \u00e8 trovato impreparato a gestire un problema epocale come quello di una pandemia diffusa in tutto il mondo ed ora deve affrontare le problematiche operative di una convivenza con \u201cun passeggero decisamente sgradito\u201d che ha imposto una riduzione dei voli di oltre il 70%. L\u2019emergenza sanitaria ha inoltre determinato anche una profonda trasformazione delle abitudini lavorative di aziende e professionisti che hanno cominciato in tutto il mondo ad utilizzare la tecnologia per svolgere il proprio lavoro a distanza, ottimizzando tempi e costi, a discapito dei viaggi di lavoro. Anche sul versante turistico, come confermato recentemente dalla IATA, ci sar\u00e0 una profonda contrazione, con un prevedibile rallentamento da 6 mesi ed un anno prima di poter tornare a viaggiare. La stima preoccupante \u00e8 di una riduzione del 50% della biglietteria aerea nel prossimo futuro. D\u2019altro canto, anche ove i passeggeri decidessero di viaggiare dovrebbero affrontare la problematica del limitato numero di posti e dei costi decisamente pi\u00f9 elevati dovuti, come detto alle misure di sicurezza. Tale ultimo profilo, potrebbe determinare anche cambiamenti logistici all\u2019interno dell\u2019aeromobile, creando inaccettabili condizioni di trasporto per i passeggeri specialmente nei voli di lungo raggio. Potrebbe essere infatti prevedibile una riduzione dei servizi per le classi economy (al fine di non aumentare eccessivamente i prezzi) e la trasformazione degli spazi imposti dalle misure di sicurezza in aree business o premium per cercare di ottimizzare in qualche modo i gi\u00e0 bassi profitti per i vettori aerei. La considerazione finale a cui porta tale breve considerazione \u00e8 che in assenza di una ripresa, gli aiuti di stato non basteranno a sostenere le compagnie aeree, che non potrebbero resistere pi\u00f9 di 6 mesi in questa condizione di stallo dovendo poi dichiarare fallimento. Tale rischio, apre una ulteriore polemica sulle scelte del governo italiano di autorizzare vettori aerei stranieri a trattenere il prezzo dei biglietti acquistati da parte dei consumatori, dietro il rilascio di un voucher, utilizzabile entro un anno dalla sua emissione, senza alcuna garanzia su tale titolo di credito o possibilit\u00e0 di riscattarlo in caso di impossibilit\u00e0 a fruirne. \u00c8 di immediata evidenza, infatti, che aver imposto un termine di validit\u00e0 limitato a 12 mesi, determinerebbe inevitabilmente, l\u2019obbligo del passeggero di utilizzare tale voucher (che non \u00e8 un biglietto ma un titolo di viaggio) per acquistare biglietteria a prezzi necessariamente pi\u00f9 elevati, condizionata alla disponibilit\u00e0 dei posti da parte del vettore aereo. \u00c8 altres\u00ec immaginabile, che i passeggeri in genere, saranno scoraggiati a viaggiare nel prossimo anno a causa delle conseguenze economiche della crisi e dei potenziali rischi di contagio durante i trasferimenti aerei, rendendo di fatto inutilizzabili i crediti trasferiti attraverso i voucher. I vettori, d\u2019altro canto, attesa la massiva emissione di voucher sarebbero in ogni caso obbligate a viaggiare, ma, in assenza di richieste ulteriori, la domanda basata solo sul riscatto dei voucher sarebbe insufficiente per garantire la prosecuzione dell\u2019attivit\u00e0 aerea.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avv. Fabio Collavini la pandemia ha cambiato le abitudini delle persone ed inevitabilmente ha prodotto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":858,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.4 (Yoast SEO v20.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pandemia riflessioni dell&#039;Avv. Fabio Collavini<\/title>\n<meta name=\"description\" content=\"Pandemia riflessioni dell&#039;Avv. Fabio Collavini\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pandemia riflessioni dell&#039;Avv. Fabio Collavini\" \/>\n<meta property=\"og:description\" content=\"Pandemia riflessioni dell&#039;Avv. Fabio Collavini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-27T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-22T21:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvaviaggio.com\/blog\/wp-content\/uploads\/2020\/12\/200628180009.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"156\" \/>\n\t<meta property=\"og:image:height\" content=\"117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"svadm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"svadm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\"},\"author\":{\"name\":\"svadm\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/person\/7a7763449297ba5001b6aa9d2f1e22b1\"},\"headline\":\"Pandemia riflessioni dell&#8217;Avv. Fabio Collavini\",\"datePublished\":\"2020-06-27T22:00:00+00:00\",\"dateModified\":\"2021-05-22T21:35:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\"},\"wordCount\":632,\"publisher\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\",\"url\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\",\"name\":\"Pandemia riflessioni dell'Avv. Fabio Collavini\",\"isPartOf\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#website\"},\"datePublished\":\"2020-06-27T22:00:00+00:00\",\"dateModified\":\"2021-05-22T21:35:54+00:00\",\"description\":\"Pandemia riflessioni dell'Avv. Fabio Collavini\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salvaviaggio.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pandemia riflessioni dell&#8217;Avv. Fabio Collavini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#website\",\"url\":\"https:\/\/www.salvaviaggio.com\/blog\/\",\"name\":\"Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salvaviaggio.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#organization\",\"name\":\"Salvaviaggio.com\",\"url\":\"https:\/\/www.salvaviaggio.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.salvaviaggio.com\/blog\/wp-content\/uploads\/2021\/05\/download.png\",\"contentUrl\":\"https:\/\/www.salvaviaggio.com\/blog\/wp-content\/uploads\/2021\/05\/download.png\",\"width\":223,\"height\":226,\"caption\":\"Salvaviaggio.com\"},\"image\":{\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/person\/7a7763449297ba5001b6aa9d2f1e22b1\",\"name\":\"svadm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/465de16360825ac8a9a2e10eba152aaca594ceba89f2c5b6161f7796584063f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/465de16360825ac8a9a2e10eba152aaca594ceba89f2c5b6161f7796584063f8?s=96&d=mm&r=g\",\"caption\":\"svadm\"},\"sameAs\":[\"https:\/\/www.salvaviaggio.com\/blog-new\"],\"url\":\"https:\/\/www.salvaviaggio.com\/blog\/author\/svadm\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pandemia riflessioni dell'Avv. Fabio Collavini","description":"Pandemia riflessioni dell'Avv. Fabio Collavini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/","og_locale":"it_IT","og_type":"article","og_title":"Pandemia riflessioni dell'Avv. Fabio Collavini","og_description":"Pandemia riflessioni dell'Avv. Fabio Collavini","og_url":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/","og_site_name":"Blog","article_published_time":"2020-06-27T22:00:00+00:00","article_modified_time":"2021-05-22T21:35:54+00:00","og_image":[{"width":156,"height":117,"url":"https:\/\/www.salvaviaggio.com\/blog\/wp-content\/uploads\/2020\/12\/200628180009.jpg","type":"image\/jpeg"}],"author":"svadm","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"svadm","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/#article","isPartOf":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/"},"author":{"name":"svadm","@id":"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/person\/7a7763449297ba5001b6aa9d2f1e22b1"},"headline":"Pandemia riflessioni dell&#8217;Avv. Fabio Collavini","datePublished":"2020-06-27T22:00:00+00:00","dateModified":"2021-05-22T21:35:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/"},"wordCount":632,"publisher":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/#organization"},"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/","url":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/","name":"Pandemia riflessioni dell'Avv. Fabio Collavini","isPartOf":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/#website"},"datePublished":"2020-06-27T22:00:00+00:00","dateModified":"2021-05-22T21:35:54+00:00","description":"Pandemia riflessioni dell'Avv. Fabio Collavini","breadcrumb":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvaviaggio.com\/blog\/corona-virus-consigli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salvaviaggio.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pandemia riflessioni dell&#8217;Avv. Fabio Collavini"}]},{"@type":"WebSite","@id":"https:\/\/www.salvaviaggio.com\/blog\/#website","url":"https:\/\/www.salvaviaggio.com\/blog\/","name":"Blog","description":"","publisher":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvaviaggio.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.salvaviaggio.com\/blog\/#organization","name":"Salvaviaggio.com","url":"https:\/\/www.salvaviaggio.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.salvaviaggio.com\/blog\/wp-content\/uploads\/2021\/05\/download.png","contentUrl":"https:\/\/www.salvaviaggio.com\/blog\/wp-content\/uploads\/2021\/05\/download.png","width":223,"height":226,"caption":"Salvaviaggio.com"},"image":{"@id":"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/person\/7a7763449297ba5001b6aa9d2f1e22b1","name":"svadm","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.salvaviaggio.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/465de16360825ac8a9a2e10eba152aaca594ceba89f2c5b6161f7796584063f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/465de16360825ac8a9a2e10eba152aaca594ceba89f2c5b6161f7796584063f8?s=96&d=mm&r=g","caption":"svadm"},"sameAs":["https:\/\/www.salvaviaggio.com\/blog-new"],"url":"https:\/\/www.salvaviaggio.com\/blog\/author\/svadm\/"}]}},"wps_subtitle":"La pandemia ha cambiato le abitudini delle persone ed inevitabilmente ha prodotto profondi cambiamenti anche nelle misure di prevenzione. Nel trasporto aereo il coronavirus ha imposto una riduzione delle rotte, specifici controlli sanitari, riduzione dei servizi ed ovviamente tariffe pi\u00f9 elevate.","_links":{"self":[{"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/posts\/857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/comments?post=857"}],"version-history":[{"count":4,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/posts\/857\/revisions"}],"predecessor-version":[{"id":1957,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/posts\/857\/revisions\/1957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/media\/858"}],"wp:attachment":[{"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/media?parent=857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/categories?post=857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvaviaggio.com\/blog\/wp-json\/wp\/v2\/tags?post=857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}